{"id":7328,"date":"2021-02-15T13:06:36","date_gmt":"2021-02-15T12:06:36","guid":{"rendered":"https:\/\/tourdera.cat\/tram\/tram-estacio-de-tren-massanes\/"},"modified":"2026-07-15T11:02:38","modified_gmt":"2026-07-15T09:02:38","slug":"tram-estacio-de-tren-massanes","status":"publish","type":"tram","link":"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/","title":{"rendered":"Section Tourdera estaci\u00f3 de tren &#8211; Massanes"},"content":{"rendered":"","protected":false},"featured_media":7329,"parent":0,"template":"","municipi":[546],"dificultat":[598],"class_list":["post-7328","tram","type-tram","status-publish","has-post-thumbnail","hentry","municipi-massanes","dificultat-facil"],"acf":[],"yoast_head":"<title>Section Tourdera estaci\u00f3 de tren - Massanes - Tourdera<\/title>\n<meta name=\"description\" content=\"Tram de la ruta de la Tordera entre l&#039;estaci\u00f3 de tren de Ma\u00e7anet-Massanes i el poble de Massanes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Section Tourdera estaci\u00f3 de tren - Massanes - Tourdera\" \/>\n<meta property=\"og:description\" content=\"Tram de la ruta de la Tordera entre l&#039;estaci\u00f3 de tren de Ma\u00e7anet-Massanes i el poble de Massanes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/\" \/>\n<meta property=\"og:site_name\" content=\"Tourdera\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T09:02:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/26a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/\",\"url\":\"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/\",\"name\":\"Section Tourdera estaci\u00f3 de tren - Massanes - Tourdera\",\"isPartOf\":{\"@id\":\"https:\/\/tourdera.cat\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/26a.jpg\",\"datePublished\":\"2021-02-15T12:06:36+00:00\",\"dateModified\":\"2026-07-15T09:02:38+00:00\",\"description\":\"Tram de la ruta de la Tordera entre l'estaci\u00f3 de tren de Ma\u00e7anet-Massanes i el poble de Massanes\",\"breadcrumb\":{\"@id\":\"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/#primaryimage\",\"url\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/26a.jpg\",\"contentUrl\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/26a.jpg\",\"width\":1024,\"height\":687,\"caption\":\"Tram estaci\u00f3 de tren - Massanes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/tourdera.cat\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Section Tourdera estaci\u00f3 de tren &#8211; Massanes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tourdera.cat\/en\/#website\",\"url\":\"https:\/\/tourdera.cat\/en\/\",\"name\":\"Tourdera\",\"description\":\"Ruta de la Tordera i Riera d&#039;Arb\u00c3\u00bacies\",\"publisher\":{\"@id\":\"https:\/\/tourdera.cat\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tourdera.cat\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tourdera.cat\/en\/#organization\",\"name\":\"Tourdera\",\"url\":\"https:\/\/tourdera.cat\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tourdera.cat\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png\",\"contentUrl\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png\",\"width\":822,\"height\":195,\"caption\":\"Tourdera\"},\"image\":{\"@id\":\"https:\/\/tourdera.cat\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"Section Tourdera estaci\u00f3 de tren - Massanes - Tourdera","description":"Tram de la ruta de la Tordera entre l'estaci\u00f3 de tren de Ma\u00e7anet-Massanes i el poble de Massanes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/","og_locale":"en_US","og_type":"article","og_title":"Section Tourdera estaci\u00f3 de tren - Massanes - Tourdera","og_description":"Tram de la ruta de la Tordera entre l'estaci\u00f3 de tren de Ma\u00e7anet-Massanes i el poble de Massanes","og_url":"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/","og_site_name":"Tourdera","article_modified_time":"2026-07-15T09:02:38+00:00","og_image":[{"width":1024,"height":687,"url":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/26a.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/","url":"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/","name":"Section Tourdera estaci\u00f3 de tren - Massanes - Tourdera","isPartOf":{"@id":"https:\/\/tourdera.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/#primaryimage"},"image":{"@id":"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/#primaryimage"},"thumbnailUrl":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/26a.jpg","datePublished":"2021-02-15T12:06:36+00:00","dateModified":"2026-07-15T09:02:38+00:00","description":"Tram de la ruta de la Tordera entre l'estaci\u00f3 de tren de Ma\u00e7anet-Massanes i el poble de Massanes","breadcrumb":{"@id":"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/#primaryimage","url":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/26a.jpg","contentUrl":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/26a.jpg","width":1024,"height":687,"caption":"Tram estaci\u00f3 de tren - Massanes"},{"@type":"BreadcrumbList","@id":"https:\/\/tourdera.cat\/en\/tram\/tram-estacio-de-tren-massanes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/tourdera.cat\/en\/"},{"@type":"ListItem","position":2,"name":"Section Tourdera estaci\u00f3 de tren &#8211; Massanes"}]},{"@type":"WebSite","@id":"https:\/\/tourdera.cat\/en\/#website","url":"https:\/\/tourdera.cat\/en\/","name":"Tourdera","description":"Ruta de la Tordera i Riera d&#039;Arb\u00c3\u00bacies","publisher":{"@id":"https:\/\/tourdera.cat\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tourdera.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tourdera.cat\/en\/#organization","name":"Tourdera","url":"https:\/\/tourdera.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tourdera.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png","contentUrl":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png","width":822,"height":195,"caption":"Tourdera"},"image":{"@id":"https:\/\/tourdera.cat\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tourdera.cat\/en\/wp-json\/wp\/v2\/tram\/7328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tourdera.cat\/en\/wp-json\/wp\/v2\/tram"}],"about":[{"href":"https:\/\/tourdera.cat\/en\/wp-json\/wp\/v2\/types\/tram"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tourdera.cat\/en\/wp-json\/wp\/v2\/media\/7329"}],"wp:attachment":[{"href":"https:\/\/tourdera.cat\/en\/wp-json\/wp\/v2\/media?parent=7328"}],"wp:term":[{"taxonomy":"municipi","embeddable":true,"href":"https:\/\/tourdera.cat\/en\/wp-json\/wp\/v2\/municipi?post=7328"},{"taxonomy":"dificultat","embeddable":true,"href":"https:\/\/tourdera.cat\/en\/wp-json\/wp\/v2\/dificultat?post=7328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}