{"id":7033,"date":"2024-04-17T12:13:26","date_gmt":"2024-04-17T10:13:26","guid":{"rendered":"https:\/\/tourdera.cat\/afectacio\/tram-fora-de-servei-enllac-vallgorguina\/"},"modified":"2026-06-22T14:19:07","modified_gmt":"2026-06-22T12:19:07","slug":"passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee","status":"publish","type":"afectacio","link":"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/","title":{"rendered":"Passage coup\u00e9 entre le Pont Cass\u00e9 et la route C-61 (liaison Vallgorguina) : d\u00e9viation propos\u00e9e"},"content":{"rendered":"<p>Le tron\u00e7on de la Tourdera correspondant \u00e0 l\u2019itin\u00e9raire de liaison entre l\u2019itin\u00e9raire principal de la route et le village de Vallgorguina pr\u00e9sente un petit tron\u00e7on temporairement hors service. Plus pr\u00e9cis\u00e9ment, le tron\u00e7on coup\u00e9 se situe dans la zone du Pont Cass\u00e9, entre les communes de Sant Celoni et Santa Maria de Palautordera, et la route C-61.<\/p>\n<p>Concr\u00e8tement, cette coupure est due aux travaux en cours dans la zone de ca l&rsquo;Alzina Nou. En raison de l\u2019ampleur des travaux \u00e0 r\u00e9aliser, le passage des personnes par ce point a \u00e9t\u00e9 totalement interrompu (raccordement au r\u00e9seau d\u2019eau potable et d\u2019assainissement, installation des branchements \u00e9lectriques et t\u00e9l\u00e9phoniques, r\u00e9seau d\u2019\u00e9clairage public, etc.). La dur\u00e9e pr\u00e9vue des travaux est de 3 \u00e0 4 mois.<\/p>\n<p>C\u2019est pourquoi deux d\u00e9viations provisoires ont \u00e9t\u00e9 mises en place, non signal\u00e9es sur le terrain, pour les usagers se dirigeant vers Vallgorguina (passage par le quartier de Moixerigues) ou pour ceux qui viennent de Vallgorguina en direction de Sant Celoni ou de Santa Maria de Palautordera (passage par l\u2019ancienne Via Provincial). Sur les fiches de chaque tron\u00e7on, entre Vallgorguina, Sant Celoni et Santa Maria de Palautordera, vous trouverez les informations d\u00e9taill\u00e9es et actualis\u00e9es :<\/p>\n<ul>\n<li>Tron\u00e7on <a href=\"https:\/\/tourdera.cat\/tram\/tram-vallgorguina-santa-maria-de-palautordera\/\" target=\"_blank\" rel=\"noopener\">Vallgorguina &#8211; Santa Maria de Palautordera<\/a>.<\/li>\n<li>Tron\u00e7on <a href=\"https:\/\/tourdera.cat\/tram\/tram-santa-maria-de-palautordera-vallgorguina\/\" target=\"_blank\" rel=\"noopener\">Santa Maria de Palautordera &#8211; Vallgorguina<\/a>.<\/li>\n<li>Tron\u00e7on <a href=\"https:\/\/tourdera.cat\/tram\/tram-sant-celoni-vallgorguina\/\" target=\"_blank\" rel=\"noopener\">Sant Celoni &#8211; Vallgorguina<\/a>.<\/li>\n<li>Tron\u00e7on <a href=\"https:\/\/tourdera.cat\/tram\/tram-vallgorguina-sant-celoni\/\" target=\"_blank\" rel=\"noopener\">Vallgorguina &#8211; Sant Celoni<\/a>.<\/li>\n<\/ul>\n<p>Nous vous prions de nous excuser pour la g\u00eane occasionn\u00e9e.<\/p>\n<figure id=\"attachment_4571\" aria-describedby=\"caption-attachment-4571\" style=\"width: 1014px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/\/IMG_0010-1024x512.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-4571 size-large\" src=\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/\/IMG_0010-1024x512.jpg\" alt=\"Travaux sur l\u2019itin\u00e9raire de liaison Vallgorguina\" width=\"1024\" height=\"512\" srcset=\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/IMG_0010-1024x512.jpg 1024w, https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/IMG_0010-300x150.jpg 300w, https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/IMG_0010-768x384.jpg 768w, https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/IMG_0010.jpg 1339w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption id=\"caption-attachment-4571\" class=\"wp-caption-text\">Travaux sur l\u2019itin\u00e9raire de liaison Vallgorguina<\/figcaption><\/figure>\n","protected":false},"featured_media":7035,"template":"","class_list":["post-7033","afectacio","type-afectacio","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<title>Passage coup\u00e9 entre le Pont Cass\u00e9 et la route C-61 (liaison Vallgorguina) : d\u00e9viation propos\u00e9e - Tourdera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Passage coup\u00e9 entre le Pont Cass\u00e9 et la route C-61 (liaison Vallgorguina) : d\u00e9viation propos\u00e9e - Tourdera\" \/>\n<meta property=\"og:description\" content=\"Le tron\u00e7on de la Tourdera correspondant \u00e0 l\u2019itin\u00e9raire de liaison entre l\u2019itin\u00e9raire principal de la route et le village de Vallgorguina pr\u00e9sente un petit tron\u00e7on temporairement hors service. Plus pr\u00e9cis\u00e9ment, le tron\u00e7on coup\u00e9 se situe dans la zone du Pont Cass\u00e9, entre les communes de Sant Celoni et Santa Maria de Palautordera, et la route ... Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/\" \/>\n<meta property=\"og:site_name\" content=\"Tourdera\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T12:19:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/desviaments-vallgorguina.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/\",\"url\":\"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/\",\"name\":\"Passage coup\u00e9 entre le Pont Cass\u00e9 et la route C-61 (liaison Vallgorguina) : d\u00e9viation propos\u00e9e - Tourdera\",\"isPartOf\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/desviaments-vallgorguina.png\",\"datePublished\":\"2024-04-17T10:13:26+00:00\",\"dateModified\":\"2026-06-22T12:19:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/#primaryimage\",\"url\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/desviaments-vallgorguina.png\",\"contentUrl\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/desviaments-vallgorguina.png\",\"width\":600,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/tourdera.cat\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Passage coup\u00e9 entre le Pont Cass\u00e9 et la route C-61 (liaison Vallgorguina) : d\u00e9viation propos\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tourdera.cat\/fr\/#website\",\"url\":\"https:\/\/tourdera.cat\/fr\/\",\"name\":\"Tourdera\",\"description\":\"Ruta de la Tordera i Riera d&#039;Arb\u00c3\u00bacies\",\"publisher\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tourdera.cat\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tourdera.cat\/fr\/#organization\",\"name\":\"Tourdera\",\"url\":\"https:\/\/tourdera.cat\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/tourdera.cat\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png\",\"contentUrl\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png\",\"width\":822,\"height\":195,\"caption\":\"Tourdera\"},\"image\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"Passage coup\u00e9 entre le Pont Cass\u00e9 et la route C-61 (liaison Vallgorguina) : d\u00e9viation propos\u00e9e - Tourdera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/","og_locale":"fr_FR","og_type":"article","og_title":"Passage coup\u00e9 entre le Pont Cass\u00e9 et la route C-61 (liaison Vallgorguina) : d\u00e9viation propos\u00e9e - Tourdera","og_description":"Le tron\u00e7on de la Tourdera correspondant \u00e0 l\u2019itin\u00e9raire de liaison entre l\u2019itin\u00e9raire principal de la route et le village de Vallgorguina pr\u00e9sente un petit tron\u00e7on temporairement hors service. Plus pr\u00e9cis\u00e9ment, le tron\u00e7on coup\u00e9 se situe dans la zone du Pont Cass\u00e9, entre les communes de Sant Celoni et Santa Maria de Palautordera, et la route ... Lire la suite","og_url":"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/","og_site_name":"Tourdera","article_modified_time":"2026-06-22T12:19:07+00:00","og_image":[{"width":600,"height":531,"url":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/desviaments-vallgorguina.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/","url":"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/","name":"Passage coup\u00e9 entre le Pont Cass\u00e9 et la route C-61 (liaison Vallgorguina) : d\u00e9viation propos\u00e9e - Tourdera","isPartOf":{"@id":"https:\/\/tourdera.cat\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/#primaryimage"},"image":{"@id":"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/#primaryimage"},"thumbnailUrl":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/desviaments-vallgorguina.png","datePublished":"2024-04-17T10:13:26+00:00","dateModified":"2026-06-22T12:19:07+00:00","breadcrumb":{"@id":"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/#primaryimage","url":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/desviaments-vallgorguina.png","contentUrl":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/desviaments-vallgorguina.png","width":600,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/tourdera.cat\/fr\/afectacio\/passage-coupe-entre-le-pont-casse-et-la-route-c-61-liaison-vallgorguina-deviation-proposee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/tourdera.cat\/fr\/"},{"@type":"ListItem","position":2,"name":"Passage coup\u00e9 entre le Pont Cass\u00e9 et la route C-61 (liaison Vallgorguina) : d\u00e9viation propos\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/tourdera.cat\/fr\/#website","url":"https:\/\/tourdera.cat\/fr\/","name":"Tourdera","description":"Ruta de la Tordera i Riera d&#039;Arb\u00c3\u00bacies","publisher":{"@id":"https:\/\/tourdera.cat\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tourdera.cat\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/tourdera.cat\/fr\/#organization","name":"Tourdera","url":"https:\/\/tourdera.cat\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tourdera.cat\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png","contentUrl":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png","width":822,"height":195,"caption":"Tourdera"},"image":{"@id":"https:\/\/tourdera.cat\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/afectacio\/7033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/afectacio"}],"about":[{"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/types\/afectacio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/media\/7035"}],"wp:attachment":[{"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/media?parent=7033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}