{"id":7129,"date":"2022-09-15T11:47:14","date_gmt":"2022-09-15T09:47:14","guid":{"rendered":"https:\/\/tourdera.cat\/afectacio\/circuleu-amb-precaucio-per-la-passera-sobre-la-riera-de-fuirosos\/"},"modified":"2026-06-22T14:30:51","modified_gmt":"2026-06-22T12:30:51","slug":"circulez-avec-prudence-passerelle-de-fuirosos","status":"publish","type":"afectacio","link":"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/","title":{"rendered":"Circulez avec prudence &#8211; Passerelle de Fuirosos"},"content":{"rendered":"<p>\u00c0 la suite de la temp\u00eate Harry, le passage de la route par la passerelle sur le ruisseau de Fuirosos doit s\u2019effectuer avec prudence, car les crues ont endommag\u00e9 la zone d\u2019acc\u00e8s sud \u00e0 la passerelle. Malgr\u00e9 cela, le passage \u00e0 pied est parfaitement possible et, \u00e0 v\u00e9lo, il faut descendre et traverser en poussant le v\u00e9lo \u00e0 la main. <figure id=\"attachment_6285\" aria-describedby=\"caption-attachment-6285\" style=\"width: 630px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/IMG_5917.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-6285\" src=\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/IMG_5917.jpeg\" alt=\"Photo : Tourdera. Acc\u00e8s endommag\u00e9 \u00e0 la passerelle sur le ruisseau de Fuirosos.\" width=\"640\" height=\"360\" srcset=\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/IMG_5917.jpeg 640w, https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/IMG_5917-300x169.jpeg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-6285\" class=\"wp-caption-text\">Photo : Tourdera. Acc\u00e8s endommag\u00e9 \u00e0 la passerelle sur le ruisseau de Fuirosos.<\/figcaption><\/figure><\/p>\n","protected":false},"featured_media":7131,"template":"","class_list":["post-7129","afectacio","type-afectacio","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<title>Circulez avec prudence - Passerelle de Fuirosos - Tourdera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Circulez avec prudence - Passerelle de Fuirosos - Tourdera\" \/>\n<meta property=\"og:description\" content=\"\u00c0 la suite de la temp\u00eate Harry, le passage de la route par la passerelle sur le ruisseau de Fuirosos doit s\u2019effectuer avec prudence, car les crues ont endommag\u00e9 la zone d\u2019acc\u00e8s sud \u00e0 la passerelle. Malgr\u00e9 cela, le passage \u00e0 pied est parfaitement possible et, \u00e0 v\u00e9lo, il faut descendre et traverser en poussant ... Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/\" \/>\n<meta property=\"og:site_name\" content=\"Tourdera\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T12:30:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/mapa-fuirosos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1276\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/\",\"url\":\"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/\",\"name\":\"Circulez avec prudence - Passerelle de Fuirosos - Tourdera\",\"isPartOf\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/mapa-fuirosos.png\",\"datePublished\":\"2022-09-15T09:47:14+00:00\",\"dateModified\":\"2026-06-22T12:30:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/#primaryimage\",\"url\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/mapa-fuirosos.png\",\"contentUrl\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/mapa-fuirosos.png\",\"width\":1276,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/tourdera.cat\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Circulez avec prudence &#8211; Passerelle de Fuirosos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tourdera.cat\/fr\/#website\",\"url\":\"https:\/\/tourdera.cat\/fr\/\",\"name\":\"Tourdera\",\"description\":\"Ruta de la Tordera i Riera d&#039;Arb\u00c3\u00bacies\",\"publisher\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tourdera.cat\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tourdera.cat\/fr\/#organization\",\"name\":\"Tourdera\",\"url\":\"https:\/\/tourdera.cat\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/tourdera.cat\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png\",\"contentUrl\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png\",\"width\":822,\"height\":195,\"caption\":\"Tourdera\"},\"image\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"Circulez avec prudence - Passerelle de Fuirosos - Tourdera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/","og_locale":"fr_FR","og_type":"article","og_title":"Circulez avec prudence - Passerelle de Fuirosos - Tourdera","og_description":"\u00c0 la suite de la temp\u00eate Harry, le passage de la route par la passerelle sur le ruisseau de Fuirosos doit s\u2019effectuer avec prudence, car les crues ont endommag\u00e9 la zone d\u2019acc\u00e8s sud \u00e0 la passerelle. Malgr\u00e9 cela, le passage \u00e0 pied est parfaitement possible et, \u00e0 v\u00e9lo, il faut descendre et traverser en poussant ... Lire la suite","og_url":"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/","og_site_name":"Tourdera","article_modified_time":"2026-06-22T12:30:51+00:00","og_image":[{"width":1276,"height":531,"url":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/mapa-fuirosos.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/","url":"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/","name":"Circulez avec prudence - Passerelle de Fuirosos - Tourdera","isPartOf":{"@id":"https:\/\/tourdera.cat\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/#primaryimage"},"image":{"@id":"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/#primaryimage"},"thumbnailUrl":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/mapa-fuirosos.png","datePublished":"2022-09-15T09:47:14+00:00","dateModified":"2026-06-22T12:30:51+00:00","breadcrumb":{"@id":"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/#primaryimage","url":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/mapa-fuirosos.png","contentUrl":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/mapa-fuirosos.png","width":1276,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/tourdera.cat\/fr\/afectacio\/circulez-avec-prudence-passerelle-de-fuirosos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/tourdera.cat\/fr\/"},{"@type":"ListItem","position":2,"name":"Circulez avec prudence &#8211; Passerelle de Fuirosos"}]},{"@type":"WebSite","@id":"https:\/\/tourdera.cat\/fr\/#website","url":"https:\/\/tourdera.cat\/fr\/","name":"Tourdera","description":"Ruta de la Tordera i Riera d&#039;Arb\u00c3\u00bacies","publisher":{"@id":"https:\/\/tourdera.cat\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tourdera.cat\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/tourdera.cat\/fr\/#organization","name":"Tourdera","url":"https:\/\/tourdera.cat\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tourdera.cat\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png","contentUrl":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png","width":822,"height":195,"caption":"Tourdera"},"image":{"@id":"https:\/\/tourdera.cat\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/afectacio\/7129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/afectacio"}],"about":[{"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/types\/afectacio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/media\/7131"}],"wp:attachment":[{"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/media?parent=7129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}