{"id":9867,"date":"2021-02-15T12:59:19","date_gmt":"2021-02-15T11:59:19","guid":{"rendered":"https:\/\/tourdera.cat\/tram\/tram-mosqueroles-montseny\/"},"modified":"2026-07-15T11:27:45","modified_gmt":"2026-07-15T09:27:45","slug":"tram-mosqueroles-montseny","status":"publish","type":"tram","link":"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/","title":{"rendered":"Section Tourdera Mosqueroles &#8211; Montseny"},"content":{"rendered":"","protected":false},"featured_media":9868,"parent":0,"template":"","municipi":[539],"dificultat":[603],"class_list":["post-9867","tram","type-tram","status-publish","has-post-thumbnail","hentry","municipi-fogars-de-montclus","dificultat-exigent"],"acf":[],"yoast_head":"<title>Section Tourdera Mosqueroles - Montseny - Tourdera<\/title>\n<meta name=\"description\" content=\"Tram de la ruta de la Tordera entre Mosqueroles i el poble de Montseny\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Section Tourdera Mosqueroles - Montseny - Tourdera\" \/>\n<meta property=\"og:description\" content=\"Tram de la ruta de la Tordera entre Mosqueroles i el poble de Montseny\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/\" \/>\n<meta property=\"og:site_name\" content=\"Tourdera\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T09:27:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/DSC_4033.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2140\" \/>\n\t<meta property=\"og:image:height\" content=\"1427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/\",\"url\":\"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/\",\"name\":\"Section Tourdera Mosqueroles - Montseny - Tourdera\",\"isPartOf\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/DSC_4033.jpg\",\"datePublished\":\"2021-02-15T11:59:19+00:00\",\"dateModified\":\"2026-07-15T09:27:45+00:00\",\"description\":\"Tram de la ruta de la Tordera entre Mosqueroles i el poble de Montseny\",\"breadcrumb\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/#primaryimage\",\"url\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/DSC_4033.jpg\",\"contentUrl\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/DSC_4033.jpg\",\"width\":2140,\"height\":1427,\"caption\":\"Tram Mosqueroles - Montseny\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/tourdera.cat\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Section Tourdera Mosqueroles &#8211; Montseny\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tourdera.cat\/fr\/#website\",\"url\":\"https:\/\/tourdera.cat\/fr\/\",\"name\":\"Tourdera\",\"description\":\"Ruta de la Tordera i Riera d&#039;Arb\u00c3\u00bacies\",\"publisher\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tourdera.cat\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tourdera.cat\/fr\/#organization\",\"name\":\"Tourdera\",\"url\":\"https:\/\/tourdera.cat\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/tourdera.cat\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png\",\"contentUrl\":\"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png\",\"width\":822,\"height\":195,\"caption\":\"Tourdera\"},\"image\":{\"@id\":\"https:\/\/tourdera.cat\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"Section Tourdera Mosqueroles - Montseny - Tourdera","description":"Tram de la ruta de la Tordera entre Mosqueroles i el poble de Montseny","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/","og_locale":"fr_FR","og_type":"article","og_title":"Section Tourdera Mosqueroles - Montseny - Tourdera","og_description":"Tram de la ruta de la Tordera entre Mosqueroles i el poble de Montseny","og_url":"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/","og_site_name":"Tourdera","article_modified_time":"2026-07-15T09:27:45+00:00","og_image":[{"width":2140,"height":1427,"url":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/DSC_4033.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/","url":"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/","name":"Section Tourdera Mosqueroles - Montseny - Tourdera","isPartOf":{"@id":"https:\/\/tourdera.cat\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/#primaryimage"},"image":{"@id":"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/#primaryimage"},"thumbnailUrl":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/DSC_4033.jpg","datePublished":"2021-02-15T11:59:19+00:00","dateModified":"2026-07-15T09:27:45+00:00","description":"Tram de la ruta de la Tordera entre Mosqueroles i el poble de Montseny","breadcrumb":{"@id":"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/#primaryimage","url":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/DSC_4033.jpg","contentUrl":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/DSC_4033.jpg","width":2140,"height":1427,"caption":"Tram Mosqueroles - Montseny"},{"@type":"BreadcrumbList","@id":"https:\/\/tourdera.cat\/fr\/tram\/tram-mosqueroles-montseny\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/tourdera.cat\/fr\/"},{"@type":"ListItem","position":2,"name":"Section Tourdera Mosqueroles &#8211; Montseny"}]},{"@type":"WebSite","@id":"https:\/\/tourdera.cat\/fr\/#website","url":"https:\/\/tourdera.cat\/fr\/","name":"Tourdera","description":"Ruta de la Tordera i Riera d&#039;Arb\u00c3\u00bacies","publisher":{"@id":"https:\/\/tourdera.cat\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tourdera.cat\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/tourdera.cat\/fr\/#organization","name":"Tourdera","url":"https:\/\/tourdera.cat\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tourdera.cat\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png","contentUrl":"https:\/\/tourdera.cat\/wp-content\/uploads\/sites\/3\/tourdera-logo.png","width":822,"height":195,"caption":"Tourdera"},"image":{"@id":"https:\/\/tourdera.cat\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/tram\/9867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/tram"}],"about":[{"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/types\/tram"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/media\/9868"}],"wp:attachment":[{"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/media?parent=9867"}],"wp:term":[{"taxonomy":"municipi","embeddable":true,"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/municipi?post=9867"},{"taxonomy":"dificultat","embeddable":true,"href":"https:\/\/tourdera.cat\/fr\/wp-json\/wp\/v2\/dificultat?post=9867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}